<div id="cont-gal-video" class="et_pb_section et_pb_section_0 et_section_regular">
						<div id="galeria-video" class="et_pb_row et_pb_row_0">
							<div class="et_pb_column et_pb_column_4_4 et_pb_column_0 et_pb_css_mix_blend_mode_passthrough et-last-child">
								<div class="et_pb_module et_pb_text et_pb_text_0 titulo-video et_pb_bg_layout_light  et_pb_text_align_left">			
									<div class="et_pb_text_inner">
										<!--<h2>DIÁLOGOS A LA CARTA - I Edición</h2>-->
									</div>
								</div> <!-- .et_pb_text --><div class="et_pb_module et_pb_video et_pb_video_0 video-gal">	
									<div class="et_pb_video_box">
										<video video controls controlsList="nodownload" oncontextmenu="return false;">
											<source src="https://socios.clubarbitraje.com/index_raw.php?modulo=petext&task=petext&action=VERvIDEO&id=6&v=Diálogos a la Carta_B. Cremades e Yves Derains.mp4&l=1&s=full#t=1" type="video/mp4">
										</video>
									</div>
								</div><div class="et_pb_module et_pb_text et_pb_text_1 desc-video et_pb_bg_layout_light  et_pb_text_align_left">
									<div class="et_pb_text_inner">
										<p><p>En la primera edici&oacute;n de Di&aacute;logos a la Carta hemos tenido la oportunidad de contar con la participaci&oacute;n de Bernardo Cremades e Yves Derains. Os invitamos a acceder al v&iacute;deo para que pod&aacute;is ver la entrevista realizada en compa&ntilde;ia de dos de los &aacute;rbitros m&aacute;s relevantes del mundo &aacute;rbitral.&nbsp;</p></p>
									</div>
								</div> <!-- .et_pb_text --></div> <!-- .et_pb_code_inner -->
								</div> <!-- .et_pb_code --></div> <!-- .et_pb_column -->
				</div> <!-- .et_pb_row -->
			</div>{"id":11904,"date":"2020-07-07T13:26:20","date_gmt":"2020-07-07T11:26:20","guid":{"rendered":"https:\/\/www.clubarbitraje.com\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/"},"modified":"2020-07-07T13:26:20","modified_gmt":"2020-07-07T11:26:20","slug":"dialogos-a-la-carta-bernardo-cremades-e-yves-derains","status":"publish","type":"post","link":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/","title":{"rendered":"Di\u00e1logos a la Carta &#8211; Bernardo Cremades e Yves Derains"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"<p>En la primera edici\u00f3n de Di\u00e1logos a la Carta, Bernardo Cremades entrevista a Yves Derains. <\/p>\n","protected":false},"author":4,"featured_media":11441,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[305],"tags":[],"class_list":["post-11904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimedia","et-has-post-format-content","et_post_format-et-post-format-standard"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Di\u00e1logos a la Carta - Bernardo Cremades e Yves Derains - CEIA \u2013 CLUB ESPA\u00d1OL E IBEROAMERICANO DEL ARBITRAJE<\/title>\n<meta name=\"description\" content=\"CEA, Club Espa\u00f1ol del Arbitraje, asociaci\u00f3n sin \u00e1nimo de lucro cuyo objetivo es promover el arbitraje como m\u00e9todo de resoluci\u00f3n de conflictos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Di\u00e1logos a la Carta - Bernardo Cremades e Yves Derains - CEIA \u2013 CLUB ESPA\u00d1OL E IBEROAMERICANO DEL ARBITRAJE\" \/>\n<meta property=\"og:description\" content=\"CEA, Club Espa\u00f1ol del Arbitraje, asociaci\u00f3n sin \u00e1nimo de lucro cuyo objetivo es promover el arbitraje como m\u00e9todo de resoluci\u00f3n de conflictos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/\" \/>\n<meta property=\"og:site_name\" content=\"CEIA \u2013 CLUB ESPA\u00d1OL E IBEROAMERICANO DEL ARBITRAJE\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-07T11:26:20+00:00\" \/>\n<meta name=\"author\" content=\"Daniella Esquivel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniella Esquivel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/\"},\"author\":{\"name\":\"Daniella Esquivel\",\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/#\\\/schema\\\/person\\\/edb623576969b9cdad23c4b51fd0d084\"},\"headline\":\"Di\u00e1logos a la Carta &#8211; Bernardo Cremades e Yves Derains\",\"datePublished\":\"2020-07-07T11:26:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/\"},\"wordCount\":13,\"image\":{\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.clubarbitraje.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cap_inter_es_Gene\u0301rico-1.jpg\",\"articleSection\":[\"Multimedia\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/\",\"url\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/\",\"name\":\"Di\u00e1logos a la Carta - Bernardo Cremades e Yves Derains - CEIA \u2013 CLUB ESPA\u00d1OL E IBEROAMERICANO DEL ARBITRAJE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.clubarbitraje.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cap_inter_es_Gene\u0301rico-1.jpg\",\"datePublished\":\"2020-07-07T11:26:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/#\\\/schema\\\/person\\\/edb623576969b9cdad23c4b51fd0d084\"},\"description\":\"CEA, Club Espa\u00f1ol del Arbitraje, asociaci\u00f3n sin \u00e1nimo de lucro cuyo objetivo es promover el arbitraje como m\u00e9todo de resoluci\u00f3n de conflictos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.clubarbitraje.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cap_inter_es_Gene\u0301rico-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.clubarbitraje.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cap_inter_es_Gene\u0301rico-1.jpg\",\"width\":598,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/pt-pt\\\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.clubarbitraje.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Di\u00e1logos a la Carta &#8211; Bernardo Cremades e Yves Derains\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/#website\",\"url\":\"https:\\\/\\\/www.clubarbitraje.com\\\/\",\"name\":\"CEIA \u2013 CLUB ESPA\u00d1OL E IBEROAMERICANO DEL ARBITRAJE\",\"description\":\"CEIA, Club Espa\u00f1ol e Iberoamericano del Arbitraje, asociaci\u00f3n sin \u00e1nimo de lucro cuyo objetivo es promover el arbitraje como m\u00e9todo de resoluci\u00f3n de conflictos.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clubarbitraje.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.clubarbitraje.com\\\/#\\\/schema\\\/person\\\/edb623576969b9cdad23c4b51fd0d084\",\"name\":\"Daniella Esquivel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c14ac6c5358c50ecc59c4d5e6f50ce6d2528d83d18176fc3be982ef7db28374?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c14ac6c5358c50ecc59c4d5e6f50ce6d2528d83d18176fc3be982ef7db28374?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c14ac6c5358c50ecc59c4d5e6f50ce6d2528d83d18176fc3be982ef7db28374?s=96&d=mm&r=g\",\"caption\":\"Daniella Esquivel\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Di\u00e1logos a la Carta - Bernardo Cremades e Yves Derains - CEIA \u2013 CLUB ESPA\u00d1OL E IBEROAMERICANO DEL ARBITRAJE","description":"CEA, Club Espa\u00f1ol del Arbitraje, asociaci\u00f3n sin \u00e1nimo de lucro cuyo objetivo es promover el arbitraje como m\u00e9todo de resoluci\u00f3n de conflictos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/","og_locale":"pt_PT","og_type":"article","og_title":"Di\u00e1logos a la Carta - Bernardo Cremades e Yves Derains - CEIA \u2013 CLUB ESPA\u00d1OL E IBEROAMERICANO DEL ARBITRAJE","og_description":"CEA, Club Espa\u00f1ol del Arbitraje, asociaci\u00f3n sin \u00e1nimo de lucro cuyo objetivo es promover el arbitraje como m\u00e9todo de resoluci\u00f3n de conflictos.","og_url":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/","og_site_name":"CEIA \u2013 CLUB ESPA\u00d1OL E IBEROAMERICANO DEL ARBITRAJE","article_published_time":"2020-07-07T11:26:20+00:00","author":"Daniella Esquivel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Daniella Esquivel"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/#article","isPartOf":{"@id":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/"},"author":{"name":"Daniella Esquivel","@id":"https:\/\/www.clubarbitraje.com\/#\/schema\/person\/edb623576969b9cdad23c4b51fd0d084"},"headline":"Di\u00e1logos a la Carta &#8211; Bernardo Cremades e Yves Derains","datePublished":"2020-07-07T11:26:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/"},"wordCount":13,"image":{"@id":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clubarbitraje.com\/wp-content\/uploads\/2019\/05\/cap_inter_es_Gene\u0301rico-1.jpg","articleSection":["Multimedia"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/","url":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/","name":"Di\u00e1logos a la Carta - Bernardo Cremades e Yves Derains - CEIA \u2013 CLUB ESPA\u00d1OL E IBEROAMERICANO DEL ARBITRAJE","isPartOf":{"@id":"https:\/\/www.clubarbitraje.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/#primaryimage"},"image":{"@id":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clubarbitraje.com\/wp-content\/uploads\/2019\/05\/cap_inter_es_Gene\u0301rico-1.jpg","datePublished":"2020-07-07T11:26:20+00:00","author":{"@id":"https:\/\/www.clubarbitraje.com\/#\/schema\/person\/edb623576969b9cdad23c4b51fd0d084"},"description":"CEA, Club Espa\u00f1ol del Arbitraje, asociaci\u00f3n sin \u00e1nimo de lucro cuyo objetivo es promover el arbitraje como m\u00e9todo de resoluci\u00f3n de conflictos.","breadcrumb":{"@id":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/#primaryimage","url":"https:\/\/www.clubarbitraje.com\/wp-content\/uploads\/2019\/05\/cap_inter_es_Gene\u0301rico-1.jpg","contentUrl":"https:\/\/www.clubarbitraje.com\/wp-content\/uploads\/2019\/05\/cap_inter_es_Gene\u0301rico-1.jpg","width":598,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.clubarbitraje.com\/pt-pt\/dialogos-a-la-carta-bernardo-cremades-e-yves-derains\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.clubarbitraje.com\/"},{"@type":"ListItem","position":2,"name":"Di\u00e1logos a la Carta &#8211; Bernardo Cremades e Yves Derains"}]},{"@type":"WebSite","@id":"https:\/\/www.clubarbitraje.com\/#website","url":"https:\/\/www.clubarbitraje.com\/","name":"CEIA \u2013 CLUB ESPA\u00d1OL E IBEROAMERICANO DEL ARBITRAJE","description":"CEIA, Club Espa\u00f1ol e Iberoamericano del Arbitraje, asociaci\u00f3n sin \u00e1nimo de lucro cuyo objetivo es promover el arbitraje como m\u00e9todo de resoluci\u00f3n de conflictos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clubarbitraje.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.clubarbitraje.com\/#\/schema\/person\/edb623576969b9cdad23c4b51fd0d084","name":"Daniella Esquivel","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/3c14ac6c5358c50ecc59c4d5e6f50ce6d2528d83d18176fc3be982ef7db28374?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3c14ac6c5358c50ecc59c4d5e6f50ce6d2528d83d18176fc3be982ef7db28374?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c14ac6c5358c50ecc59c4d5e6f50ce6d2528d83d18176fc3be982ef7db28374?s=96&d=mm&r=g","caption":"Daniella Esquivel"}}]}},"_links":{"self":[{"href":"https:\/\/www.clubarbitraje.com\/pt-pt\/wp-json\/wp\/v2\/posts\/11904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clubarbitraje.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubarbitraje.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubarbitraje.com\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubarbitraje.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=11904"}],"version-history":[{"count":0,"href":"https:\/\/www.clubarbitraje.com\/pt-pt\/wp-json\/wp\/v2\/posts\/11904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clubarbitraje.com\/pt-pt\/wp-json\/wp\/v2\/media\/11441"}],"wp:attachment":[{"href":"https:\/\/www.clubarbitraje.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=11904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubarbitraje.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=11904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubarbitraje.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=11904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}